{"id":7915,"date":"2026-07-15T08:30:51","date_gmt":"2026-07-15T06:30:51","guid":{"rendered":"https:\/\/johann-strauss-apotheke.at\/?p=7915"},"modified":"2026-07-15T08:30:51","modified_gmt":"2026-07-15T06:30:51","slug":"klima-nedeniyle-goz-kurulugu","status":"publish","type":"post","link":"https:\/\/johann-strauss-apotheke.at\/tr\/trockene-augen-bei-klimaanlage\/","title":{"rendered":"Kuru g\u00f6zler"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1778488007678 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095699992\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Trockene Augen durch Klimaanlagen<\/h1>\n<h2>Was passiert eigentlich?<\/h2>\n<p>Klimaanlagen sorgen an hei\u00dfen Tagen f\u00fcr angenehme Temperaturen, entziehen der Raumluft jedoch gleichzeitig Feuchtigkeit. Genau das kann unseren Augen zu schaffen machen. Die trockene Luft beschleunigt die Verdunstung des sch\u00fctzenden Tr\u00e4nenfilms, sodass die empfindliche Augenoberfl\u00e4che nicht mehr ausreichend befeuchtet wird. Besonders deutlich macht sich das in B\u00fcros, Autos oder Flugzeugen bemerkbar. Wer zus\u00e4tzlich viele Stunden am Computer arbeitet, verst\u00e4rkt diesen Effekt oft unbewusst: Beim konzentrierten Blick auf den Bildschirm blinzeln wir deutlich seltener, wodurch sich der Tr\u00e4nenfilm nicht mehr gleichm\u00e4\u00dfig \u00fcber das Auge verteilt. Die Folge sind trockene, gereizte oder brennende Augen, die sich h\u00e4ufig gegen Ende des Arbeitstages bemerkbar machen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_right wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-2.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (2)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-1.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (1)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095771088\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Der Tr\u00e4nenfilm ist ein ausgekl\u00fcgeltes Schutzsystem<\/h2>\n<p>Entgegen der weit verbreiteten Annahme bestehen Tr\u00e4nen nicht nur aus Wasser. Der Tr\u00e4nenfilm ist ein komplexes Schutzsystem, das aus drei funktionellen Schichten besteht. Die \u00e4u\u00dferste Schicht enth\u00e4lt Fette (Lipide), die von den Meibom-Dr\u00fcsen am Lidrand gebildet werden und verhindern, dass die Tr\u00e4nenfl\u00fcssigkeit zu schnell verdunstet. Darunter befindet sich die w\u00e4ssrige Schicht, die den gr\u00f6\u00dften Anteil des Tr\u00e4nenfilms ausmacht. Sie versorgt die Hornhaut mit Sauerstoff und N\u00e4hrstoffen, h\u00e4lt die Augenoberfl\u00e4che feucht und enth\u00e4lt zudem Stoffe, die Krankheitserreger abwehren. Die innerste Muzinschicht sorgt schlie\u00dflich daf\u00fcr, dass sich die Tr\u00e4nen gleichm\u00e4\u00dfig auf der Augenoberfl\u00e4che verteilen und dort gut haften k\u00f6nnen. Ist eine dieser Schichten gest\u00f6rt oder verdunstet die Tr\u00e4nenfl\u00fcssigkeit zu rasch, wird die Augenoberfl\u00e4che anf\u00e4lliger f\u00fcr Reizungen und Entz\u00fcndungen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095821460\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Diese Beschwerden sprechen f\u00fcr trockene Augen<\/h2>\n<p>Die Symptome entwickeln sich h\u00e4ufig schleichend. Viele Betroffene berichten zun\u00e4chst \u00fcber ein Brennen oder Stechen der Augen, sp\u00e4ter kommt oft ein Fremdk\u00f6rper- oder Sandkorngef\u00fchl hinzu. Die Augen k\u00f6nnen ger\u00f6tet sein, schneller erm\u00fcden oder zeitweise verschwommen sehen, wobei sich die Sicht nach einigen Lidschl\u00e4gen meist wieder verbessert. Ein Ph\u00e4nomen sorgt dabei h\u00e4ufig f\u00fcr Verwirrung: Trockene Augen k\u00f6nnen paradoxerweise sogar verst\u00e4rkt tr\u00e4nen. Die gereizte Augenoberfl\u00e4che l\u00f6st einen reflektorischen Tr\u00e4nenfluss aus, diese Tr\u00e4nen besitzen jedoch nicht die richtige Zusammensetzung, um den instabilen Tr\u00e4nenfilm dauerhaft zu ersetzen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-3.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (3)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095839329\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Welche Augentropfen helfen wirklich?<\/h2>\n<p>Nicht jedes trockene Auge hat dieselbe Ursache. Deshalb unterscheiden sich auch die verf\u00fcgbaren Tr\u00e4nenersatzmittel. Pr\u00e4parate mit Hyalurons\u00e4ure z\u00e4hlen zu den am h\u00e4ufigsten eingesetzten Produkten, da sie gro\u00dfe Mengen Wasser binden und lange auf der Augenoberfl\u00e4che haften. Dadurch eignen sie sich besonders bei leichten bis mittelschweren Beschwerden. Andere Wirkstoffe wie Carboxymethylcellulose oder Hypromellose erh\u00f6hen die Viskosit\u00e4t der Tr\u00e4nenfl\u00fcssigkeit und sorgen ebenfalls f\u00fcr eine l\u00e4nger anhaltende Befeuchtung. Bei gereizten Schleimh\u00e4uten k\u00f6nnen Kombinationen mit Dexpanthenol die Regeneration unterst\u00fctzen. Liegt die Ursache vor allem in einer gest\u00f6rten Lipidschicht, etwa bei einer Meibom-Dr\u00fcsen-Dysfunktion, sind lipidhaltige Augentropfen oder Sprays h\u00e4ufig besser geeignet, da sie die Verdunstung der Tr\u00e4nenfl\u00fcssigkeit reduzieren. F\u00fcr ausgepr\u00e4gte Beschwerden oder die Nacht kommen Augengele oder Augensalben infrage, die l\u00e4nger auf dem Auge verbleiben, allerdings vor\u00fcbergehend die Sicht etwas verschwimmen lassen k\u00f6nnen. Wer regelm\u00e4\u00dfig Augentropfen ben\u00f6tigt, sollte m\u00f6glichst konservierungsmittelfreie Pr\u00e4parate w\u00e4hlen, da diese die Augenoberfl\u00e4che langfristig weniger reizen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095883033\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Kleine Tipps mit gro\u00dfer Wirkung<\/h2>\n<p>Auch die richtige Anwendung entscheidet dar\u00fcber, wie gut Augentropfen wirken. Vor dem Eintropfen sollten die H\u00e4nde gr\u00fcndlich gewaschen werden. Wichtig ist au\u00dferdem, dass die Tropferspitze weder das Auge noch die Wimpern ber\u00fchrt, um Verunreinigungen zu vermeiden. Ein einzelner Tropfen gen\u00fcgt v\u00f6llig \u2013 mehr kann das Auge ohnehin nicht aufnehmen. Nach dem Eintropfen empfiehlt es sich, das Auge sanft zu schlie\u00dfen und den inneren Augenwinkel f\u00fcr etwa eine Minute leicht zuzudr\u00fccken. Dadurch verbleibt der Wirkstoff l\u00e4nger auf der Augenoberfl\u00e4che und flie\u00dft weniger \u00fcber den Tr\u00e4nenkanal ab. Werden mehrere Augentropfen verwendet, sollte zwischen den einzelnen Pr\u00e4paraten ein Abstand von f\u00fcnf bis zehn Minuten eingehalten werden. Augensalben werden grunds\u00e4tzlich zuletzt angewendet.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-4.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (4)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-5.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (5)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095913070\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Das kann man vorbeugend tun<\/h2>\n<p>Schon kleine Ver\u00e4nderungen im Alltag k\u00f6nnen trockenen Augen vorbeugen. L\u00fcftungsd\u00fcsen von Klimaanlagen sollten m\u00f6glichst nicht direkt auf das Gesicht gerichtet sein, da der Luftstrom den Tr\u00e4nenfilm zus\u00e4tzlich austrocknet. Gerade bei l\u00e4ngerer Bildschirmarbeit lohnt es sich au\u00dferdem, regelm\u00e4\u00dfig bewusst vollst\u00e4ndig zu blinzeln und den Blick immer wieder in die Ferne schweifen zu lassen. Die sogenannte 20-20-20-Regel kann dabei helfen: Alle 20 Minuten f\u00fcr etwa 20 Sekunden auf einen Punkt in rund sechs Metern Entfernung schauen. Ausreichendes Trinken, eine angenehme Luftfeuchtigkeit in Innenr\u00e4umen und gegebenenfalls eine Pause von Kontaktlinsen k\u00f6nnen die Beschwerden zus\u00e4tzlich lindern.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784095952894\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Wann \u00e4rztliche Hilfe notwendig ist<\/h2>\n<p>Trockene Augen sind zwar meist harmlos, dennoch gibt es Situationen, in denen eine augen\u00e4rztliche Abkl\u00e4rung wichtig ist. Treten starke Schmerzen, eine pl\u00f6tzliche Sehverschlechterung, ausgepr\u00e4gte Lichtempfindlichkeit oder eitriges Sekret auf, sollte rasch \u00e4rztlicher Rat eingeholt werden. Gleiches gilt, wenn nur ein Auge betroffen ist, nach einer Verletzung Beschwerden auftreten oder die Symptome trotz geeigneter Behandlung \u00fcber l\u00e4ngere Zeit bestehen bleiben. In der Apotheke l\u00e4sst sich h\u00e4ufig bereits gut einsch\u00e4tzen, welches Tr\u00e4nenersatzmittel am besten geeignet ist und ob eine Selbstbehandlung ausreicht oder eine augen\u00e4rztliche Untersuchung empfohlen werden sollte.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-6.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (6)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1719336639663 bg-image-ps-inherit\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element inherit inherit\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper default  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-7.jpg\" width=\"600\" height=\"706\" alt=\"Trockene Augen bei Klimaanlage mit Augentropfen lindern\" title=\"Trockene Augen_Klimaanlage_Augentropfen_Johann Strauss Apotheke (7)\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1784096017914\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Apotheken-Tipps<\/h2>\n<p><strong>Kontaktlinsen und trockene Augen<\/strong><\/p>\n<p>Trockene Augen k\u00f6nnen das Tragen von Kontaktlinsen deutlich unangenehmer machen. Nicht alle Augentropfen sind f\u00fcr Kontaktlinsen geeignet. Achten Sie auf entsprechende Hinweise oder verwenden Sie konservierungsmittelfreie Pr\u00e4parate. Bei st\u00e4rkeren Beschwerden kann es sinnvoll sein, vor\u00fcbergehend auf eine Brille umzusteigen.<\/p>\n<p><strong>Klimaanlage im Auto<\/strong><\/p>\n<p>Richten Sie die L\u00fcftungsd\u00fcsen m\u00f6glichst nicht direkt auf das Gesicht oder die Augen. Der permanente Luftstrom beschleunigt die Verdunstung des Tr\u00e4nenfilms und kann Beschwerden deutlich verst\u00e4rken.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Yaz aylar\u0131nda g\u00f6zlerimizin neden \u00f6zellikle ac\u0131 \u00e7ekti\u011fi.<\/p>","protected":false},"author":4,"featured_media":7926,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[1],"tags":[80,309,90,310,311],"class_list":["post-7915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-apotheke","tag-augentropfen","tag-johann-strauss-apotheke","tag-kontaktlinse","tag-trockene-augen"],"rttpg_featured_image_url":{"full":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8.jpg",980,980,false],"landscape":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8.jpg",980,980,false],"portraits":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8.jpg",980,980,false],"thumbnail":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8-300x300.jpg",300,300,true],"medium":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8-680x440.jpg",680,440,true],"large":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8-980x525.jpg",640,343,true],"1536x1536":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8.jpg",980,980,false],"2048x2048":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8.jpg",980,980,false],"trp-custom-language-flag":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8-12x12.jpg",12,12,true],"unfinityplus-screenshot":["https:\/\/johann-strauss-apotheke.at\/wp-content\/uploads\/2026\/07\/Trockene-Augen_Klimaanlage_Augentropfen_Johann-Strauss-Apotheke-8-260x465.jpg",260,465,true]},"rttpg_author":{"display_name":"marketing@johann-strauss-apotheke.at","author_link":"https:\/\/johann-strauss-apotheke.at\/tr\/author\/marketingjohann-strauss-apotheke-at\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/johann-strauss-apotheke.at\/tr\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","rttpg_excerpt":"Warum unsere Augen im Sommer besonders leiden.","_links":{"self":[{"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/posts\/7915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/comments?post=7915"}],"version-history":[{"count":3,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/posts\/7915\/revisions"}],"predecessor-version":[{"id":7927,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/posts\/7915\/revisions\/7927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/media\/7926"}],"wp:attachment":[{"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/media?parent=7915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/categories?post=7915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/johann-strauss-apotheke.at\/tr\/wp-json\/wp\/v2\/tags?post=7915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}